{"id":542,"count":8,"description":"<p class=\"whitespace-pre-wrap break-words\">Plonge dans l'univers d\u00e9jant\u00e9 de GYM Manager avec notre s\u00e9rie de Let's Play en fran\u00e7ais ! D\u00e9couvre les hauts et les bas de la gestion d'une salle de sport, de la cr\u00e9ation de ta premi\u00e8re salle jusqu'aux d\u00e9fis les plus fous.<\/p>\r\n<p class=\"whitespace-pre-wrap break-words\">Follow our adventures episode by episode, as we take on difficult customers, temperamental equipment and even psychopathic security guards! Learn the tricks of the trade, from decorating your venue to managing your staff, and including some unorthodox marketing techniques.<\/p>\r\n<p class=\"whitespace-pre-wrap break-words\">Que tu sois fan de jeux de gestion, passionn\u00e9 de fitness ou simplement \u00e0 la recherche d'un bon divertissement, notre s\u00e9rie GYM Manager t'offre une exp\u00e9rience unique et hilarante dans le monde du fitness virtuel.<\/p>\r\n<p class=\"whitespace-pre-wrap break-words\">Subscribe, comment and share so you don't miss out on this crazy sporting and entrepreneurial adventure!<\/p>","link":"https:\/\/tycoonterritory.fr\/en\/category\/tycoon-games\/gym-manager-fr-lets-play\/","name":"GYM Manager [FR] \u2013 Let\u2019s Play","slug":"gym-manager-fr-lets-play","taxonomy":"category","parent":548,"meta":[],"_links":{"self":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/categories\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/categories\/548"}],"wp:post_type":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts?categories=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}