{"id":1248,"date":"2024-08-05T16:17:00","date_gmt":"2024-08-05T14:17:00","guid":{"rendered":"https:\/\/tycoonterritory.fr\/?p=1248"},"modified":"2024-08-05T16:17:04","modified_gmt":"2024-08-05T14:17:04","slug":"blockbuster-inc-fr-jai-mis-un-megabar-a-cote-de-la-salle-de-cours-mauvaise-idee-10","status":"publish","type":"post","link":"https:\/\/tycoonterritory.fr\/en\/blockbuster-inc-fr-jai-mis-un-megabar-a-cote-de-la-salle-de-cours-mauvaise-idee-10\/","title":{"rendered":"Blockbuster Inc. [FR] J&rsquo;ai mis un MEGABAR \u00e0 c\u00f4t\u00e9 de la SALLE DE COURS&#8230; Mauvaise id\u00e9e ? #10"},"content":{"rendered":"<!--presto-player:video_id=160--><figure class=\"wp-block-video presto-block-video  presto-provider-youtube\" style=\"--plyr-color-main: var(--presto-player-highlight-color, #e50914); --plyr-captions-background: #453a3b; --presto-player-logo-width: 150px; \">\n\t<presto-player \n\t\tpreset='{&quot;id&quot;:6,&quot;name&quot;:&quot;My YT&quot;,&quot;slug&quot;:&quot;my-yt&quot;,&quot;icon&quot;:&quot;&quot;,&quot;skin&quot;:&quot;modern&quot;,&quot;play-large&quot;:true,&quot;rewind&quot;:true,&quot;play&quot;:true,&quot;fast-forward&quot;:true,&quot;progress&quot;:true,&quot;current-time&quot;:true,&quot;mute&quot;:true,&quot;volume&quot;:true,&quot;speed&quot;:true,&quot;pip&quot;:false,&quot;fullscreen&quot;:true,&quot;captions&quot;:true,&quot;reset_on_end&quot;:false,&quot;auto_hide&quot;:true,&quot;captions_enabled&quot;:true,&quot;save_player_position&quot;:true,&quot;sticky_scroll&quot;:true,&quot;sticky_scroll_position&quot;:&quot;center right&quot;,&quot;on_video_end&quot;:&quot;go-to-start&quot;,&quot;play_video_viewport&quot;:true,&quot;hide_youtube&quot;:true,&quot;lazy_load_youtube&quot;:true,&quot;hide_logo&quot;:true,&quot;border_radius&quot;:0,&quot;caption_style&quot;:&quot;default&quot;,&quot;caption_background&quot;:&quot;#453a3b&quot;,&quot;is_locked&quot;:false,&quot;cta&quot;:{&quot;enabled&quot;:false,&quot;percentage&quot;:100,&quot;show_rewatch&quot;:true,&quot;show_skip&quot;:true,&quot;headline&quot;:&quot;Envie de plus de vid\\u00e9o ?&quot;,&quot;bottom_text&quot;:&quot;&quot;,&quot;show_button&quot;:true,&quot;button_text&quot;:&quot;S&#039;abonner \\u00e0 la chaine YouTube&quot;,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;,&quot;background_opacity&quot;:0,&quot;button_link&quot;:{&quot;id&quot;:&quot;&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkLbauqU9Xpsg0P-sAz6EVA&quot;,&quot;type&quot;:&quot;&quot;,&quot;opensInNewTab&quot;:true},&quot;button_radius&quot;:0},&quot;watermark&quot;:{&quot;enabled&quot;:false,&quot;text&quot;:&quot;&quot;,&quot;backgroundColor&quot;:&quot;&quot;,&quot;color&quot;:&quot;&quot;,&quot;opacity&quot;:0,&quot;position&quot;:&quot;&quot;},&quot;search&quot;:{&quot;enabled&quot;:false,&quot;minMatchCharLength&quot;:1,&quot;threshold&quot;:0.3,&quot;placeholder&quot;:&quot;Search&quot;},&quot;email_collection&quot;:{&quot;enabled&quot;:false,&quot;behavior&quot;:&quot;pause&quot;,&quot;percentage&quot;:0,&quot;allow_skip&quot;:false,&quot;provider&quot;:&quot;&quot;,&quot;provider_list&quot;:&quot;&quot;,&quot;provider_tag&quot;:&quot;&quot;,&quot;border_radius&quot;:0,&quot;headline&quot;:&quot;&quot;,&quot;bottom_text&quot;:&quot;&quot;,&quot;button_text&quot;:&quot;&quot;,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;},&quot;action_bar&quot;:{&quot;enabled&quot;:false,&quot;percentage_start&quot;:0,&quot;text&quot;:&quot;Like this?&quot;,&quot;background_color&quot;:&quot;&quot;,&quot;button_type&quot;:&quot;none&quot;,&quot;button_count&quot;:false,&quot;button_text&quot;:&quot;Click Here&quot;,&quot;button_radius&quot;:0,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;,&quot;button_link&quot;:{&quot;id&quot;:&quot;&quot;,&quot;url&quot;:&quot;&quot;,&quot;type&quot;:&quot;&quot;,&quot;opensInNewTab&quot;:false}},&quot;created_by&quot;:1,&quot;created_at&quot;:&quot;2023-11-17 20:44:10&quot;,&quot;updated_at&quot;:&quot;2024-08-07 12:25:06&quot;,&quot;deleted_at&quot;:&quot;&quot;,&quot;show_time_elapsed&quot;:true}'\n\t\tbranding='{&quot;logo&quot;:&quot;&quot;,&quot;color&quot;:&quot;#e50914&quot;,&quot;logo_width&quot;:150,&quot;player_css&quot;:&quot;&quot;}'\n\t\tchapters='[]'\n\t\toverlays='[]'\n\t\ttracks='[]'\n\t\tblock-attributes='{&quot;playsInline&quot;:true,&quot;id&quot;:160,&quot;src&quot;:&quot;https:\\\/\\\/youtu.be\\\/cfW46zqJCRE&quot;,&quot;preset&quot;:6,&quot;video_id&quot;:&quot;cfW46zqJCRE&quot;,&quot;TrpContentRestriction&quot;:{&quot;restriction_type&quot;:&quot;exclude&quot;,&quot;selected_languages&quot;:[],&quot;panel_open&quot;:true},&quot;title&quot;:&quot;https:\\\/\\\/youtu.be\\\/cfW46zqJCRE&quot;}'\n\t\tanalytics='1'\n\t\tautomations\t\tprovider='youtube'\n\t\t\t\tid=\"presto-player-1\"\n\t\tsrc=\"\/\/www.youtube.com\/embed\/cfW46zqJCRE?iv_load_policy=3&amp;modestbranding=1&amp;playinline=1&amp;showinfo=0&amp;rel=0&amp;enablejsapi=1\"\n\t\tmedia-title=\"https:\/\/youtu.be\/cfW46zqJCRE\"\n\t\tcss=\"\"\n\t\tclass=\"presto-video-id-160 presto-preset-id-6 skin-modern caption-style-default\"\n\t\tskin=\"modern\" \n\t\ticon-url=\"https:\/\/tycoonterritory.fr\/wp-content\/plugins\/presto-player\/img\/sprite.svg\" \n\t\tpreload=\"\" \n\t\tposter=\"\"\n\t\tyoutube=\"{&quot;noCookie&quot;:false,&quot;channelId&quot;:&quot;&quot;,&quot;show_count&quot;:false}\"\n\t\tprovider-video-id=\"cfW46zqJCRE\"\n\t\tvideo-id=\"160\"\n\t\tlazy-load-youtube\t\tvideo-attributes='{}'\n\t\tplaysinline\t\t\t\t>\n\t\t\n\n\t<\/presto-player>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\">Quand le Cin\u00e9ma Rencontre l&rsquo;Open Bar : L&rsquo;Exp\u00e9rience Ultime de Formation<\/h2>\n\n\n\n<p>Ladies and gentlemen, film buffs and cocktail lovers, fasten your seatbelts! In this epic episode of our Blockbuster Inc. saga, we're breaking new ground in the world of entertainment. Our mission today? To create an employee's paradise... or perhaps their hell. Who knows?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">The Machiavellian Plan: A Megabar within Chalk's Reach<\/h3>\n\n\n\n<p>Imaginez un instant : vous \u00eates en plein cours sur \u00ab\u00a0L&rsquo;Art Subtil du Dialogue Shakespearien\u00a0\u00bb, et juste \u00e0 c\u00f4t\u00e9, le son enivrant d&rsquo;un shaker qui pr\u00e9pare des Mojitos. Bienvenue dans notre nouvelle r\u00e9alit\u00e9 !<\/p>\n\n\n\n<p>Why put a megabar next to the classroom? Well, why not? After all, the <a href=\"https:\/\/tycoonterritory.fr\/en\/big-ambitions-fr-une-boite-de-nuit-sans-bar-encore-une-ouverture-catastrophique-82\/\">creativity<\/a> ne na\u00eet-elle pas de l&rsquo;adversit\u00e9\u2026 ou de l&rsquo;ivresse ?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">The Ingredients of our Madness :<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>A bar worthy of the biggest casinos in Las Vegas<\/li>\n\n\n\n<li>Des billards pour \u00ab\u00a0stimuler la r\u00e9flexion strat\u00e9gique\u00a0\u00bb<\/li>\n\n\n\n<li>A jukebox, because the <a href=\"https:\/\/tycoonterritory.fr\/en\/big-ambitions-fr-je-pars-en-fievre-acheteuse-dimmeuble-04\/\">music<\/a> softens morals (and covers snoring)<\/li>\n\n\n\n<li>Snack dispensers for post-cocktail snacks<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">The Unexpected Consequences<\/h3>\n\n\n\n<p>\u00c9tonnamment, notre d\u00e9cision n&rsquo;a pas que des inconv\u00e9nients :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les cours sur les effets sp\u00e9ciaux n&rsquo;ont jamais \u00e9t\u00e9 aussi r\u00e9alistes (merci les hallucinations)<\/li>\n\n\n\n<li>Les sc\u00e9naristes trouvent enfin l&rsquo;inspiration pour leurs com\u00e9dies<\/li>\n\n\n\n<li>Les acteurs s&rsquo;entra\u00eenent \u00e0 jouer des personnages ivres\u2026 en permanence<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">L&rsquo;Art D\u00e9licat de la Formation&#8230; ou de la D\u00e9formation ?<\/h3>\n\n\n\n<p>Pendant que nos cascadeurs s&rsquo;entra\u00eenent \u00e0 tomber avec gr\u00e2ce (ou pas), nos employ\u00e9s jonglent entre formations intensives et happy hours prolong\u00e9es. Qui a dit que l&rsquo;apprentissage devait \u00eatre ennuyeux ?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Our philosophy :<\/h4>\n\n\n\n<p>\u00ab\u00a0Un esprit sain dans un corps\u2026 l\u00e9g\u00e8rement \u00e9m\u00e9ch\u00e9.\u00a0\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">The Oscars are reaching out to us<\/h3>\n\n\n\n<p>Against all the odds, our unconventional approach is bearing fruit:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Meilleur Studio : \u00c9videmment, qui d&rsquo;autre ?<\/li>\n\n\n\n<li>Best Television Programme: Because reality surpasses fiction<\/li>\n\n\n\n<li>Studio le Plus Rentable : Qui aurait cru que l&rsquo;alcool \u00e9tait si lucratif ?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Le Futur s&rsquo;Annonce&#8230; Flou, mais Prometteur<\/h3>\n\n\n\n<p>Avec 28 000 nouveaux fans (probablement attir\u00e9s par l&rsquo;odeur de la vodka), notre empire du divertissement ne cesse de cro\u00eetre. Prochaine \u00e9tape ? Peut-\u00eatre un parc d&rsquo;attractions \u00e0 th\u00e8me \u00ab\u00a0Gueule de bois\u00a0\u00bb ?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion: Genius or madness?<\/h2>\n\n\n\n<p>Alors, mettre un m\u00e9gabar \u00e0 c\u00f4t\u00e9 de la salle de cours \u00e9tait-il une mauvaise id\u00e9e ? Le jury est encore\u2026 en train de cuver. Mais une chose est s\u00fbre : notre studio n&rsquo;a jamais \u00e9t\u00e9 aussi anim\u00e9 !<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute pour le prochain \u00e9pisode, o\u00f9 nous tenterons peut-\u00eatre de tourner un film enti\u00e8rement sous l&rsquo;eau\u2026 ou sous l&#8217;emprise de l&rsquo;alcool, selon ce qui arrivera en premier.<\/p>\n\n\n\n<p>N&rsquo;oubliez pas de liker, commenter et partager si vous aussi vous pensez que l&rsquo;apprentissage et les loisirs font bon m\u00e9nage\u2026 ou si vous voulez simplement voir jusqu&rsquo;o\u00f9 ira notre folie !<\/p>\n\n\n\n<p>Et rappelez-vous : dans l&rsquo;univers de Blockbuster Inc., la seule limite est votre imagination (et peut-\u00eatre le taux d&rsquo;alcool\u00e9mie l\u00e9gal, mais chut, on n&rsquo;en parlera pas).<\/p>","protected":false},"excerpt":{"rendered":"<p>Quand le Cin\u00e9ma Rencontre l&rsquo;Open Bar : L&rsquo;Exp\u00e9rience Ultime de Formation Mesdames et messieurs, cin\u00e9philes et amateurs de cocktails, attachez vos ceintures ! Dans cet \u00e9pisode \u00e9pique de notre saga Blockbuster Inc., nous franchissons une nouvelle fronti\u00e8re dans le monde du divertissement. Notre mission du jour ? Cr\u00e9er le paradis des employ\u00e9s\u2026 ou peut-\u00eatre leur&#8230;<\/p>","protected":false},"author":1,"featured_media":1252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[543],"tags":[],"class_list":["post-1248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockbuster-inc-fr-lets-play"],"jetpack_featured_media_url":"https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48.png","uagb_featured_image_src":{"full":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48.png",1280,720,false],"thumbnail":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48-150x150.png",150,150,true],"medium":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48-300x169.png",300,169,true],"medium_large":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48-768x432.png",768,432,true],"large":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48-1024x576.png",1024,576,true],"1536x1536":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48.png",1280,720,false],"2048x2048":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48.png",1280,720,false],"trp-custom-language-flag":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2024\/08\/Big-Ambitions-FR-On-demarre-avec-1-en-poche-01-48-18x10.png",18,10,true]},"uagb_author_info":{"display_name":"hello@wpmarket.fr","author_link":"#"},"uagb_comment_info":0,"uagb_excerpt":"Quand le Cin\u00e9ma Rencontre l&rsquo;Open Bar : L&rsquo;Exp\u00e9rience Ultime de Formation Mesdames et messieurs, cin\u00e9philes et amateurs de cocktails, attachez vos ceintures ! Dans cet \u00e9pisode \u00e9pique de notre saga Blockbuster Inc., nous franchissons une nouvelle fronti\u00e8re dans le monde du divertissement. Notre mission du jour ? Cr\u00e9er le paradis des employ\u00e9s\u2026 ou peut-\u00eatre leur...","_links":{"self":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/1248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/comments?post=1248"}],"version-history":[{"count":1,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/1248\/revisions"}],"predecessor-version":[{"id":1253,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/1248\/revisions\/1253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/media\/1252"}],"wp:attachment":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/media?parent=1248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/categories?post=1248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/tags?post=1248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}