{"id":312,"date":"2023-05-02T18:00:00","date_gmt":"2023-05-02T16:00:00","guid":{"rendered":"https:\/\/tycoonterritory.fr\/?p=312"},"modified":"2023-11-17T20:58:45","modified_gmt":"2023-11-17T19:58:45","slug":"big-ambitions-fr-mon-qg-devient-trop-petit-43","status":"publish","type":"post","link":"https:\/\/tycoonterritory.fr\/en\/big-ambitions-fr-mon-qg-devient-trop-petit-43\/","title":{"rendered":"Big Ambitions [FR] Mon QG devient trop petit ! #43"},"content":{"rendered":"<!--presto-player:video_id=33--><figure class=\"wp-block-video presto-block-video  presto-provider-youtube\" style=\"--plyr-color-main: var(--presto-player-highlight-color, #e50914); --plyr-captions-background: #453a3b; --presto-player-logo-width: 150px; \">\n\t<presto-player \n\t\tpreset='{&quot;id&quot;:6,&quot;name&quot;:&quot;My YT&quot;,&quot;slug&quot;:&quot;my-yt&quot;,&quot;icon&quot;:&quot;&quot;,&quot;skin&quot;:&quot;modern&quot;,&quot;play-large&quot;:true,&quot;rewind&quot;:true,&quot;play&quot;:true,&quot;fast-forward&quot;:true,&quot;progress&quot;:true,&quot;current-time&quot;:true,&quot;mute&quot;:true,&quot;volume&quot;:true,&quot;speed&quot;:true,&quot;pip&quot;:false,&quot;fullscreen&quot;:true,&quot;captions&quot;:true,&quot;reset_on_end&quot;:false,&quot;auto_hide&quot;:true,&quot;captions_enabled&quot;:true,&quot;save_player_position&quot;:true,&quot;sticky_scroll&quot;:true,&quot;sticky_scroll_position&quot;:&quot;center right&quot;,&quot;on_video_end&quot;:&quot;go-to-start&quot;,&quot;play_video_viewport&quot;:true,&quot;hide_youtube&quot;:true,&quot;lazy_load_youtube&quot;:true,&quot;hide_logo&quot;:true,&quot;border_radius&quot;:0,&quot;caption_style&quot;:&quot;default&quot;,&quot;caption_background&quot;:&quot;#453a3b&quot;,&quot;is_locked&quot;:false,&quot;cta&quot;:{&quot;enabled&quot;:false,&quot;percentage&quot;:100,&quot;show_rewatch&quot;:true,&quot;show_skip&quot;:true,&quot;headline&quot;:&quot;Envie de plus de vid\\u00e9o ?&quot;,&quot;bottom_text&quot;:&quot;&quot;,&quot;show_button&quot;:true,&quot;button_text&quot;:&quot;S&#039;abonner \\u00e0 la chaine YouTube&quot;,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;,&quot;background_opacity&quot;:0,&quot;button_link&quot;:{&quot;id&quot;:&quot;&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkLbauqU9Xpsg0P-sAz6EVA&quot;,&quot;type&quot;:&quot;&quot;,&quot;opensInNewTab&quot;:true},&quot;button_radius&quot;:0},&quot;watermark&quot;:{&quot;enabled&quot;:false,&quot;text&quot;:&quot;&quot;,&quot;backgroundColor&quot;:&quot;&quot;,&quot;color&quot;:&quot;&quot;,&quot;opacity&quot;:0,&quot;position&quot;:&quot;&quot;},&quot;search&quot;:{&quot;enabled&quot;:false,&quot;minMatchCharLength&quot;:1,&quot;threshold&quot;:0.3,&quot;placeholder&quot;:&quot;Search&quot;},&quot;email_collection&quot;:{&quot;enabled&quot;:false,&quot;behavior&quot;:&quot;pause&quot;,&quot;percentage&quot;:0,&quot;allow_skip&quot;:false,&quot;provider&quot;:&quot;&quot;,&quot;provider_list&quot;:&quot;&quot;,&quot;provider_tag&quot;:&quot;&quot;,&quot;border_radius&quot;:0,&quot;headline&quot;:&quot;&quot;,&quot;bottom_text&quot;:&quot;&quot;,&quot;button_text&quot;:&quot;&quot;,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;},&quot;action_bar&quot;:{&quot;enabled&quot;:false,&quot;percentage_start&quot;:0,&quot;text&quot;:&quot;Like this?&quot;,&quot;background_color&quot;:&quot;&quot;,&quot;button_type&quot;:&quot;none&quot;,&quot;button_count&quot;:false,&quot;button_text&quot;:&quot;Click Here&quot;,&quot;button_radius&quot;:0,&quot;button_color&quot;:&quot;&quot;,&quot;button_text_color&quot;:&quot;&quot;,&quot;button_link&quot;:{&quot;id&quot;:&quot;&quot;,&quot;url&quot;:&quot;&quot;,&quot;type&quot;:&quot;&quot;,&quot;opensInNewTab&quot;:false}},&quot;created_by&quot;:1,&quot;created_at&quot;:&quot;2023-11-17 20:44:10&quot;,&quot;updated_at&quot;:&quot;2024-08-07 12:25:06&quot;,&quot;deleted_at&quot;:&quot;&quot;,&quot;show_time_elapsed&quot;:true}'\n\t\tbranding='{&quot;logo&quot;:&quot;&quot;,&quot;color&quot;:&quot;#e50914&quot;,&quot;logo_width&quot;:150,&quot;player_css&quot;:&quot;&quot;}'\n\t\tchapters='[]'\n\t\toverlays='[]'\n\t\ttracks='[]'\n\t\tblock-attributes='{&quot;playsInline&quot;:true,&quot;id&quot;:33,&quot;src&quot;:&quot;https:\\\/\\\/youtu.be\\\/4u_DUFrka9M&quot;,&quot;preset&quot;:6,&quot;video_id&quot;:&quot;4u_DUFrka9M&quot;,&quot;visibility&quot;:&quot;public&quot;,&quot;color&quot;:&quot;#00b3ff&quot;,&quot;mutedPreview&quot;:{&quot;enabled&quot;:false,&quot;captions&quot;:false},&quot;mutedOverlay&quot;:{&quot;enabled&quot;:false,&quot;src&quot;:&quot;&quot;,&quot;width&quot;:200,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5}},&quot;mutedOverlayType&quot;:&quot;text&quot;,&quot;mutedOverlayText&quot;:&quot;Click to play&quot;,&quot;mutedOverlayImageWidth&quot;:200,&quot;chapters&quot;:[],&quot;overlays&quot;:[],&quot;tracks&quot;:[],&quot;TrpContentRestriction&quot;:{&quot;restriction_type&quot;:&quot;exclude&quot;,&quot;selected_languages&quot;:[],&quot;panel_open&quot;:true},&quot;title&quot;:&quot;Big Ambitions [FR] Mon QG devient trop petit ! #43&quot;}'\n\t\tanalytics='1'\n\t\tautomations\t\tprovider='youtube'\n\t\t\t\tid=\"presto-player-1\"\n\t\tsrc=\"\/\/www.youtube.com\/embed\/4u_DUFrka9M?iv_load_policy=3&amp;modestbranding=1&amp;playinline=1&amp;showinfo=0&amp;rel=0&amp;enablejsapi=1\"\n\t\tmedia-title=\"Big Ambitions [FR] Mon QG devient trop petit ! #43\"\n\t\tcss=\"\"\n\t\tclass=\"presto-video-id-33 presto-preset-id-6 skin-modern caption-style-default\"\n\t\tskin=\"modern\" \n\t\ticon-url=\"https:\/\/tycoonterritory.fr\/wp-content\/plugins\/presto-player\/img\/sprite.svg\" \n\t\tpreload=\"\" \n\t\tposter=\"\"\n\t\tyoutube=\"{&quot;noCookie&quot;:false,&quot;channelId&quot;:&quot;&quot;,&quot;show_count&quot;:false}\"\n\t\tprovider-video-id=\"4u_DUFrka9M\"\n\t\tvideo-id=\"33\"\n\t\tlazy-load-youtube\t\tvideo-attributes='{}'\n\t\tplaysinline\t\t\t\t>\n\t\t\n\n\t<\/presto-player>\n<\/figure>\n\n\n<h1 class=\"wp-block-heading\">R\u00e9sum\u00e9 de la vid\u00e9o : Big Ambitions, gestion du QG et pr\u00e9paration de l&rsquo;avenir<\/h1>\n\n\n\n<p>Salut \u00e0 tous ! Dans cette vid\u00e9o, je vous montre comment je g\u00e8re mon QG dans <strong><a href=\"https:\/\/tycoonterritory.fr\/en\/big-ambitions-fr-on-enchaine-la-chaine-logistique-71\/\">Big Ambitions<\/a><\/strong> et pr\u00e9pare l&rsquo;avenir de mon empire financier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Inspecter et agrandir mon QG<\/h2>\n\n\n\n<p>Apr\u00e8s \u00eatre sorti de ma <a href=\"https:\/\/tycoonterritory.fr\/en\/comment-je-chasse-les-voitures-de-mon-centre-ville-16\/\">voiture<\/a> qui a besoin de r\u00e9parations, j&rsquo;ai inspect\u00e9 le travail de mes employ\u00e9s et me suis rendu compte que mon QG commence \u00e0 \u00eatre \u00e0 l&rsquo;\u00e9troit. J&rsquo;ai d\u00e9cid\u00e9 d&rsquo;agrandir mon QG en ajoutant des bureaux et des chaises, command\u00e9s chez <a href=\"https:\/\/tycoonterritory.fr\/en\/big-ambitions-fr-ca-recrute-fort-65\/\">Ikea<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">G\u00e9rer le personnel<\/h2>\n\n\n\n<p>J&rsquo;ai v\u00e9rifi\u00e9 si tout le monde avait bien son quota d&rsquo;heures et si les employ\u00e9s \u00e9taient heureux. Il ne me reste que trois slots de libre, donc il va falloir trouver une solution rapidement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Projet d&rsquo;un nouveau QG<\/h2>\n\n\n\n<p>Je pense qu&rsquo;il est temps d&rsquo;envisager un nouveau QG pour accueillir les emplois les plus simples \u00e0 transf\u00e9rer, comme les emplois de DRH. Cela me permettrait de mieux g\u00e9rer mes entreprises.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Achat d&rsquo;un bureau \u00e0 Broadway<\/h2>\n\n\n\n<p>Dans cette vid\u00e9o, j&rsquo;ai r\u00e9v\u00e9l\u00e9 que j&rsquo;ai d\u00e9j\u00e0 achet\u00e9 un bureau \u00e0 Broadway pour mon futur QG. Je vous montrerai tout cela dans le prochain \u00e9pisode.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9parer ma voiture<\/h2>\n\n\n\n<p>Avant de finir, j&rsquo;ai d\u00e9cid\u00e9 de r\u00e9parer ma voiture qui \u00e9tait en mauvais \u00e9tat. Il est important de prendre soin de ses biens !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion et avenir<\/h2>\n\n\n\n<p>Dans cette vid\u00e9o, j&rsquo;ai pr\u00e9par\u00e9 l&rsquo;avenir de mon entreprise en agrandissant mon QG actuel et en envisageant un nouveau QG pour g\u00e9rer encore plus d&rsquo;entreprises. Mes <strong>big ambitions<\/strong> ne font que grandir !<\/p>\n\n\n\n<p>N&rsquo;h\u00e9sitez pas \u00e0 liker cette vid\u00e9o, \u00e0 laisser un commentaire et \u00e0 vous abonner \u00e0 ma cha\u00eene pour ne pas manquer les prochains \u00e9pisodes de Big Ambitions. \u00c0 demain, ciao ciao !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 de la vid\u00e9o : Big Ambitions, gestion du QG et pr\u00e9paration de l&rsquo;avenir Salut \u00e0 tous ! Dans cette vid\u00e9o, je vous montre comment je g\u00e8re mon QG dans Big Ambitions et pr\u00e9pare l&rsquo;avenir de mon empire financier. Inspecter et agrandir mon QG Apr\u00e8s \u00eatre sorti de ma voiture qui a besoin de r\u00e9parations,&#8230;<\/p>","protected":false},"author":1,"featured_media":313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[1],"tags":[],"class_list":["post-312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-ambitions-fr-lets-play"],"jetpack_featured_media_url":"https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41.png","uagb_featured_image_src":{"full":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41.png",1280,720,false],"thumbnail":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41-150x150.png",150,150,true],"medium":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41-300x169.png",300,169,true],"medium_large":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41-768x432.png",768,432,true],"large":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41-1024x576.png",1024,576,true],"1536x1536":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41.png",1280,720,false],"2048x2048":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41.png",1280,720,false],"trp-custom-language-flag":["https:\/\/tycoonterritory.fr\/wp-content\/uploads\/2023\/04\/Big-Ambitions-FR-Une-viree-virile-en-ville-41.png",18,10,false]},"uagb_author_info":{"display_name":"hello@wpmarket.fr","author_link":"#"},"uagb_comment_info":0,"uagb_excerpt":"R\u00e9sum\u00e9 de la vid\u00e9o : Big Ambitions, gestion du QG et pr\u00e9paration de l&rsquo;avenir Salut \u00e0 tous ! Dans cette vid\u00e9o, je vous montre comment je g\u00e8re mon QG dans Big Ambitions et pr\u00e9pare l&rsquo;avenir de mon empire financier. Inspecter et agrandir mon QG Apr\u00e8s \u00eatre sorti de ma voiture qui a besoin de r\u00e9parations,...","_links":{"self":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/comments?post=312"}],"version-history":[{"count":4,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/312\/revisions"}],"predecessor-version":[{"id":861,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/posts\/312\/revisions\/861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/media\/313"}],"wp:attachment":[{"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/media?parent=312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/categories?post=312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tycoonterritory.fr\/en\/wp-json\/wp\/v2\/tags?post=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}